{"id":76669,"date":"2025-12-04T07:21:07","date_gmt":"2025-12-04T07:21:07","guid":{"rendered":"https:\/\/pala-hack.com\/palas-padel\/nox-at10-luxury-genius-18k-alum-2026\/"},"modified":"2026-04-20T07:59:06","modified_gmt":"2026-04-20T07:59:06","slug":"nox-at10-luxury-genius-18k-alum-2026","status":"publish","type":"pala","link":"https:\/\/pala-hack.com\/fr\/raquettes-padel\/nox\/nox-at10-luxury-genius-18k-alum-agustin-tapia-2026\/","title":{"rendered":"Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Pala<\/p>\n","protected":false},"author":1,"featured_media":76727,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"marca_pala":[604],"tipo_jugador":[684,665],"forma_pala":[704],"nivel_jugador":[719],"balance_pala":[753],"tacto_pala":[774],"superficie_pala":[789],"tipo_juego":[802],"pros_pala":[],"contras_pala":[],"class_list":["post-76669","pala","type-pala","status-publish","has-post-thumbnail","hentry","marca_pala-nox","tipo_jugador-femme","tipo_jugador-homme","forma_pala-larme","nivel_jugador-avance","balance_pala-moyen","tacto_pala-moyen","superficie_pala-rugueuse","tipo_juego-polyvalent"],"acf":{"nucleo":"Eva Black MLD","cara":"Carbon Fiber 18K Alum","marco":"Carbon","acabado":"Relieve 3D","temporada":2026,"potencia":8.25,"punto_dulce":9.5,"salida_bola":8.75,"control":8.75,"manejabilidad":9.75,"puntuacion_total":9,"analisis":"<p>La Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026 est le mod\u00e8le signature d'Agust\u00edn Tapia pour une tranche de joueurs avanc\u00e9s qui recherchent un v\u00e9ritable \u00e9quilibre entre contr\u00f4le, maniabilit\u00e9 et capacit\u00e9 \u00e0 frapper quand il le faut. D\u00e8s les premi\u00e8res minutes, elle nous a laiss\u00e9 une sensation tr\u00e8s claire : <strong>elle est \u00e9tonnamment agile pour une raquette avec une intention offensive<\/strong>. Cette version s'adresse aux joueurs avanc\u00e9s qui souhaitent bien se d\u00e9placer, se positionner au filet et d\u00e9finir avec fermet\u00e9. Cette raquette s'adapte bien aux joueurs qui pr\u00e9f\u00e8rent contr\u00f4ler le jeu \u00e0 des rythmes moyens et bas, tout en maintenant de la puissance lorsque le coup est bien pr\u00e9par\u00e9.<\/p>\n\n<h2>Premi\u00e8res Sensations avec la Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026<\/h2>\n<p>La base technique de cette version m\u00e9lange <strong>carbone 18K aluminis\u00e9<\/strong> avec <strong>gomme MLD Black EVA<\/strong>, et cela se traduit par un toucher moyen tr\u00e8s reconnaissable d\u00e8s la premi\u00e8re balle. Nous ne sommes pas face \u00e0 une raquette \u00e0 toucher doux ni \u00e0 une raquette \u00e0 toucher extr\u00eamement sec, mais \u00e0 un point interm\u00e9diaire qui nous permet de bien sentir la balle et de jouer en toute s\u00e9curit\u00e9. Le carbone aluminis\u00e9 apporte une rigidit\u00e9 du plan assez propre et, de plus, aide \u00e0 ce que les sensations varient moins avec les changements de temp\u00e9rature. D\u00e8s que nous la prenons en main, on sent qu'elle est con\u00e7ue pour se d\u00e9placer rapidement, avec une construction \u00e9quilibr\u00e9e et un comportement tr\u00e8s stable.<\/p>\n<p>La premi\u00e8re chose qui nous a frapp\u00e9s a \u00e9t\u00e9 sa <strong>grande maniabilit\u00e9<\/strong>. Elle est \u00e9tonnamment agile pour une raquette qui a \u00e9galement des aspirations offensives, et cela rend l'adaptation rapide dans presque n'importe quelle situation sur le court. Le toucher moyen permet de bien sentir la balle sans que la raquette soit excessivement douce, ce qui nous a donn\u00e9 une <strong>sensation de contr\u00f4le tr\u00e8s constante<\/strong>. La sortie de balle n'est pas automatique comme avec une raquette plus r\u00e9active ou plus orient\u00e9e vers la puissance pure, mais en revanche, elle r\u00e9pond de mani\u00e8re solide, propre et avec un tr\u00e8s bon ressenti \u00e0 l'impact.<\/p>\n<p>Nous avons \u00e9galement appr\u00e9ci\u00e9 le travail de la finition de surface, car elle combine <strong>relief 3D et rugueux sablonneux<\/strong> pour am\u00e9liorer l'adh\u00e9rence de la balle. Ce n'est pas un d\u00e9tail d\u00e9coratif : dans un jeu r\u00e9el, on remarque que la balle glisse moins et que le contact a plus d'intention lorsque nous cherchons \u00e0 couper ou \u00e0 lifter. Le poids standard entre 360 et 375 grammes, associ\u00e9 \u00e0 un <strong>\u00e9quilibre moyen-bas<\/strong>, s'inscrit tr\u00e8s bien dans cette id\u00e9e d'une raquette offensive mais facile \u00e0 d\u00e9placer. La sensation g\u00e9n\u00e9rale est celle d'une AT10 tr\u00e8s \u00e9quilibr\u00e9e, avec plus d'arguments en mati\u00e8re de contr\u00f4le et de confort que de puissance brute.<\/p>\n\n<h3>Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026 Depuis le Fond de Court<\/h3>\n<p>Depuis l'arri\u00e8re, c'est l\u00e0 que nous avons le plus clairement vu son caract\u00e8re. La sortie de balle montre qu'elle n'est pas ultra r\u00e9active sans la participation du joueur, et cela nous donne une marge pour <strong>contr\u00f4ler les lobs, les retours de mur et les changements de rythme<\/strong> avec une assez grande pr\u00e9cision. En d\u00e9fense \u00e0 rythme moyen, elle se comporte avec assurance et ne nous a pas donn\u00e9 cette sensation inconfortable que la balle reste courte par surprise. En fait, d\u00e8s que nous acc\u00e9l\u00e9rons un peu le bras, la profondeur appara\u00eet assez facilement et la transition vers le filet se fait naturellement.<\/p>\n<p>Son <strong>point doux large<\/strong> fait la diff\u00e9rence dans cette zone. Il est bien centr\u00e9, facile \u00e0 trouver et fait que les coups l\u00e9g\u00e8rement d\u00e9centr\u00e9s p\u00e9nalisent moins que d'habitude, ce qui est tr\u00e8s appr\u00e9ciable lorsque nous d\u00e9fendons avec peu de temps. La combinaison du carbone 18K aluminis\u00e9 avec la gomme MLD Black EVA offre une r\u00e9ponse ferme et contr\u00f4lable, avec une bonne consistance de frappe mais sans devenir une raquette dure. Pour nous, c'est l'une de ses meilleures vertus : elle ne donne pas la balle, mais ne punit pas trop non plus.<\/p>\n<p>\u00c0 des rythmes moyens et moyens bas, elle se d\u00e9place particuli\u00e8rement bien. Sans avoir \u00e0 pousser trop fort ni \u00e0 allonger excessivement le geste, nous obtenons une <strong>sortie de balle suffisante et tr\u00e8s utilisable<\/strong>, m\u00eame meilleure dans ce contexte que la EA10 Ventus Hybrid ou la AT10 12K Extreme. Lorsque l'\u00e9change s'acc\u00e9l\u00e8re beaucoup, nous remarquons qu'elle absorbe plus le coup que ces deux-l\u00e0 et que la vitesse de la balle diminue d'un cran. N\u00e9anmoins, la sensation de contr\u00f4le en jouant rapidement reste tr\u00e8s bonne, ce qui compte aussi beaucoup.<\/p>\n<p>L'autre point important \u00e0 l'arri\u00e8re est la maniabilit\u00e9. C'est une raquette assez rapide sur le court, avec un \u00e9quilibre moyen-bas et tr\u00e8s peu de punition physique dans des d\u00e9fenses inconfortables. Cela dit, comme elle n'a pas beaucoup de poids \u00e0 la pointe, si nous ne tirons pas bien de la t\u00eate vers le bas, il peut arriver que la balle s'\u00e9l\u00e8ve plus que nous le souhaitons sur certains coups fermes en bas. Ce n'est pas un d\u00e9faut grave, mais c'est une adaptation technique \u00e0 garder \u00e0 l'esprit.<\/p>\n\n<h3>Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026 Au Filet<\/h3>\n<p>Le double rugueux 3D et sablonneux a beaucoup de protagonisme en haut. En vol\u00e9e, en bandeja et en vibora, la raquette se d\u00e9place naturellement, maintient sa fermet\u00e9 et le plan ne se tord pas, ce qui nous permet d'obtenir une <strong>r\u00e9ponse propre et stable<\/strong> m\u00eame avec un geste court. Dans les vol\u00e9es coup\u00e9es et les amortis, on sent que la balle accroche bien, avec une bonne longueur et sans demander trop d'effort. La transition du fond au filet, de plus, se fait tr\u00e8s fluide gr\u00e2ce \u00e0 la facilit\u00e9 de placement rapide.<\/p>\n<p>Ici, la maniabilit\u00e9 est \u00e0 nouveau l'un de ses points forts. Celui qui vole se sent \u00e0 l'aise et rapide, et \u00e0 rythme moyen ou moyen bas, il suffit \u00e0 peine d'accompagner pour que la balle arrive en profondeur. En bandeja, nous avons beaucoup aim\u00e9 car elle combine une bonne sortie avec du contr\u00f4le, et le rugueux fait que la balle glisse moins et gagne un peu plus d'intention. En vibora, elle fonctionne \u00e9galement bien, avec <strong>une bonne adh\u00e9rence et plus de profondeur<\/strong>, bien qu'elle demande d'acc\u00e9l\u00e9rer le bras pour que la balle avance vraiment.<\/p>\n<p>Lorsque nous augmentons beaucoup la vitesse du geste, son c\u00f4t\u00e9 plus technique appara\u00eet. Si vous aimez jouer tr\u00e8s vite en haut, il faut bien tirer de la pointe vers le bas pour que la balle ne flotte pas ni ne sorte trop lin\u00e9aire. L\u00e0, le syst\u00e8me de poids aide beaucoup : en pla\u00e7ant du poids \u00e0 la t\u00eate, la raquette tombe mieux vers le bas et am\u00e9liore la finition tant en vol\u00e9e qu'en smash. Par rapport \u00e0 la version pr\u00e9c\u00e9dente, le rugueux se sent mieux et le contr\u00f4le de la balle en viboras et en bandejas nous a sembl\u00e9 plus affin\u00e9.<\/p>\n\n<h3>Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026 Au Smash<\/h3>\n<p>Au smash, la puissance est pr\u00e9sente, mais nous ne sommes pas face \u00e0 une raquette ultra offensive ni \u00e0 l'une des plus explosives du march\u00e9. Avec un bon armement du coup, on peut sortir des <strong>plans tendus<\/strong> et, surtout, des smashes par 3 ou lift\u00e9s assez s\u00e9rieux, car le rugueux aide \u00e0 ce que la balle accroche et monte mieux apr\u00e8s le rebond. Si nous entrons tard ou si le geste n'est pas bien construit, cela demande plus d'effort qu'une AT10 12K Extreme ou une EA10 Ventus Hybrid. Au smash plat, cette diff\u00e9rence se fait plus sentir : la balle s'enfonce un peu plus et sort moins, bien que le comportement reste lin\u00e9aire et progressif \u00e0 des vitesses \u00e9lev\u00e9es. Avec des poids \u00e0 la t\u00eate, la finition vers le bas s'am\u00e9liore et c'est particuli\u00e8rement appr\u00e9ci\u00e9 dans ce jeu a\u00e9rien o\u00f9 nous voulons un suppl\u00e9ment d'aide.<\/p>\n\n<h2>Puissance et Contr\u00f4le de la Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026<\/h2>\n<p>Ce qui d\u00e9finit le mieux cette Nox est son <strong>\u00e9quilibre entre maniabilit\u00e9 et performance offensive<\/strong>. Ce n'est pas la raquette la plus puissante du march\u00e9 ni celle qui offre le plus de sortie de balle, mais c'est l'une de celles qui nous permettent de jouer avec beaucoup de confiance car presque tout fonctionne bien. Le carbone 18K aluminis\u00e9 apporte de la fermet\u00e9, de la stabilit\u00e9 et une rigidit\u00e9 du plan tr\u00e8s contr\u00f4l\u00e9e, tandis que la gomme MLD Black EVA donne une sensation de toucher moyen avec une r\u00e9cup\u00e9ration rapide et sans duret\u00e9 excessive. Le r\u00e9sultat est une raquette qui fonctionne mieux \u00e0 des rythmes moyens et moyens bas, o\u00f9 elle m\u00e9lange pr\u00e9cision, stabilit\u00e9 et une puissance suffisante pour le joueur technique.<\/p>\n<p>En termes de contr\u00f4le, nous avons trouv\u00e9 que c'\u00e9tait un mod\u00e8le tr\u00e8s s\u00e9rieux. Ne pas \u00eatre ultra r\u00e9active aide beaucoup \u00e0 g\u00e9rer les lobs, les retours de mur et les changements de rythme, et lorsque nous acc\u00e9l\u00e9rons fort, elle ne donne pas cette sensation que la balle s'enfonce trop dans la face. En attaque, le rugueux et le syst\u00e8me de poids ajoutent des nuances utiles car ils am\u00e9liorent l'adh\u00e9rence en bandejas et en viboras et permettent d'ajuster un peu plus le comportement de la t\u00eate. Si nous la comparons \u00e0 la EA10 Ventus Hybrid, celle-ci a un toucher plus sec et rigide et r\u00e9pond mieux lorsque nous voulons une fermet\u00e9 maximale ; cette AT10 18K, en revanche, nous a sembl\u00e9 <strong>plus confortable et plus facile \u00e0 d\u00e9placer<\/strong>.<\/p>\n\n<h3>Point doux de la Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026<\/h3>\n<p>Le <strong>sweet spot<\/strong> est l\u00e9g\u00e8rement au-dessus de la norme en taille et, de plus, tr\u00e8s bien r\u00e9parti dans la zone centrale. Cela fait que les impacts d\u00e9centr\u00e9s ne s'\u00e9loignent pas trop du jeu et que nous pouvons d\u00e9fendre ou bloquer avec plus de confiance. Par rapport \u00e0 la version 2025, elle maintient un niveau tr\u00e8s \u00e9lev\u00e9 et nous a donn\u00e9 l'impression d'\u00eatre tout aussi bien optimis\u00e9e, voire un peu mieux. Seulement dans la zone moyenne haute de la face, le coup se sent plus sec et avec moins de sortie.<\/p>\n\n<h3>Maniabilit\u00e9 et Confort de la Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026<\/h3>\n<p>La sensation en main est celle d'une raquette <strong>tr\u00e8s agile et tr\u00e8s rapide \u00e0 d\u00e9placer<\/strong>, surtout sans les poids plac\u00e9s. Cet \u00e9quilibre moyen-bas fait qu'elle n'est pas physique et qu'elle r\u00e9pond bien dans des \u00e9changes rapides, des blocages et des transitions. Le syst\u00e8me de poids nous a plu car il permet de personnaliser l'\u00e9quilibre selon ce que chaque joueur recherche : sans eux, elle gagne en vitesse de mains, avec eux, elle perd un peu de maniabilit\u00e9 mais ajoute du contr\u00f4le et de la stabilit\u00e9. Cela ne change pas la personnalit\u00e9 du mod\u00e8le, mais affine beaucoup le comportement en haut.<\/p>\n<p>En termes de confort, il y a aussi des d\u00e9tails bien r\u00e9solus. Le <strong>pull system<\/strong>, avec des bandes en caoutchouc \u00e0 l'int\u00e9rieur du manche, est con\u00e7u pour r\u00e9duire les vibrations et s'accorde bien avec ce toucher moyen qui n'est pas agressif. Le manche est standard, avec une corde interchangeable et un bracelet ajustable par un prisonnier en caoutchouc, ce qui est pratique pour ceux qui attachent beaucoup d'importance \u00e0 cet ajustement. Parmi les raquettes de duret\u00e9 moyenne, nous pensons que c'est une option particuli\u00e8rement agr\u00e9able pour ceux qui veulent de la performance sans que la raquette ne leur demande trop physiquement.<\/p>\n\n<h3>Qualit\u00e9\/Prix de la Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026<\/h3>\n<p>Son PVP officiel est de <strong>390 \u20ac<\/strong>. Cela la place clairement dans la <strong>gamme professionnelle\/top<\/strong>, o\u00f9 il est normal d'exiger des mat\u00e9riaux premium, des technologies propres et une performance tr\u00e8s affin\u00e9e pour le joueur avanc\u00e9. Cette AT10 les a : carbone 18K aluminis\u00e9, gomme MLD Black EVA, double rugueux, syst\u00e8me de poids et un ensemble tr\u00e8s \u00e9quilibr\u00e9. Cela dit, pour la diff\u00e9rence par rapport \u00e0 la version pr\u00e9c\u00e9dente, nous ne ferions pas le changement juste pour changer si le rugueux am\u00e9lior\u00e9 n'est pas quelque chose de vraiment important dans votre jeu.<\/p>\n<p>Si vous voulez le dernier cri de Nox et que vous appr\u00e9ciez la meilleure adh\u00e9rence de balle avec la possibilit\u00e9 d'ajuster les poids, l'investissement a du sens. Si vous venez de la 2025 et que vous \u00e9tiez d\u00e9j\u00e0 \u00e0 l'aise avec elle, nous pensons que c'est un achat \u00e0 bien r\u00e9fl\u00e9chir.<\/p>\n\n<h3>Pour qui est la Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026 ?<\/h3>\n<p>Nous la voyons tr\u00e8s clairement pour <strong>des joueurs avanc\u00e9s<\/strong> qui recherchent une raquette polyvalente, maniable et avec un toucher moyen, capable de bien performer tant en d\u00e9fense qu'en prenant le filet. Elle s'adapte particuli\u00e8rement \u00e0 ceux qui jouent \u00e0 un rythme moyen ou moyen bas, qui appr\u00e9cient la pr\u00e9cision et qui veulent une raquette qui leur permette de bien se d\u00e9placer et de d\u00e9finir avec fermet\u00e9 lorsqu'ils en ont l'occasion. Nous pensons \u00e9galement que c'est une option int\u00e9ressante pour les joueurs ayant des probl\u00e8mes de coude qui ont besoin de confort, d'une bonne sortie de balle utilisable et d'une raquette qui ne soit pas lourde sur le court. Si de plus, vous avez le niveau technique pour bien pr\u00e9parer le coup, vous en tirerez beaucoup plus de jus en smash et en jeu a\u00e9rien.<\/p>\n<p>Nous ne la recommanderions pas \u00e0 ceux qui recherchent <strong>une puissance maximale<\/strong>, une raquette ultra offensive ou une r\u00e9ponse tr\u00e8s r\u00e9active d\u00e8s le premier contact. Ce n'est pas non plus le meilleur choix pour ceux qui pr\u00e9f\u00e8rent un toucher tr\u00e8s doux ou qui ne veulent pas s'adapter \u00e0 tirer de la pointe vers le bas dans des attaques rapides. Par rapport \u00e0 une AT10 12K Extreme ou une EA10 Ventus Hybrid, celle-ci joue plus la carte de l'\u00e9quilibre et de la maniabilit\u00e9 que celle de la frappe pure. Si c'est exactement ce que vous recherchez, cela a beaucoup de sens.<\/p>\n\n<h3>Avantages et Inconv\u00e9nients de la Nox AT10 Luxury Genius 18K Alum Agust\u00edn Tapia 2026<\/h3>\n<ul>\n  <li><strong>\u2713<\/strong> Grande maniabilit\u00e9 pour \u00eatre une raquette avec des aspirations offensives.<\/li>\n  <li><strong>\u2713<\/strong> Toucher moyen avec une sensation de s\u00e9curit\u00e9 et un contr\u00f4le tr\u00e8s utilisable.<\/li>\n  <li><strong>\u2713<\/strong> Point doux large et bien centr\u00e9 qui pardonne beaucoup.<\/li>\n  <li><strong>\u2713<\/strong> Carbone 18K aluminis\u00e9 avec un coup consistant et stable.<\/li>\n  <li><strong>\u2713<\/strong> Rugueux 3D et sablonneux qui am\u00e9liore l'adh\u00e9rence en viboras, bandejas et vol\u00e9es coup\u00e9es.<\/li>\n  <li><strong>\u2713<\/strong> Syst\u00e8me de poids pour ajuster l'\u00e9quilibre et la finition du coup.<\/li>\n  <li><strong>\u2713<\/strong> Tr\u00e8s bonne performance \u00e0 des rythmes moyens et moyens bas.<\/li>\n  <li><strong>\u2713<\/strong> Bonne r\u00e9ponse sur les smashes par 3 et lift\u00e9s pour les joueurs techniques.<\/li>\n<\/ul>\n<ul>\n  <li><strong>\u2717<\/strong> Ne fait pas partie des raquettes les plus puissantes ni les plus r\u00e9actives du march\u00e9.<\/li>\n  <li><strong>\u2717<\/strong> Au smash plat, la balle s'enfonce plus et sort moins que dans des mod\u00e8les plus offensifs.<\/li>\n  <li><strong>\u2717<\/strong> \u00c0 un rythme rapide depuis le fond, elle donne moins de vitesse de balle que la EA10 Ventus Hybrid ou la AT10 12K Extreme.<\/li>\n  <li><strong>\u2717<\/strong> Si nous ne tirons pas bien de la pointe vers le bas, la balle peut flotter plus que pr\u00e9vu en attaque.<\/li>\n  <li><strong>\u2717<\/strong> La zone moyenne haute de la face se sent plus s\u00e8che et avec moins de sortie.<\/li>\n  <li><strong>\u2717<\/strong> Avec des poids, elle gagne en stabilit\u00e9, mais perd une partie de sa maniabilit\u00e9 naturelle.<\/li>\n<\/ul>\n<p>La raquette offre un bon \u00e9quilibre entre <strong>contr\u00f4le, agilit\u00e9 et maniement<\/strong>, id\u00e9al pour les joueurs avanc\u00e9s qui pr\u00e9f\u00e8rent la pr\u00e9cision \u00e0 la puissance brute. Elle se d\u00e9place merveilleusement bien, a un point doux agr\u00e9able et permet de jouer avec intention en haut si la technique est pr\u00e9sente. Ce n'est pas l'AT10 pour ceux qui recherchent la frappe la plus percutante, mais c'est une option tr\u00e8s compl\u00e8te pour bien performer dans presque n'importe quelle zone du court.<\/p>","pvpr":390,"mejor_precio_url":"https:\/\/www.amazon.es\/dp\/B0FX4M8T89?&tag=tennis-hack-21","mejor_precio":327.6,"disponibilidad":1,"porcentaje_descuento":16,"scrape_tradeinn":"","url_tradeinn":"https:\/\/tnkdbf.tradeinn.com\/ts\/i5034676\/tsc?amc=con.blbn.503976.515016.14119793&rmd=3&trg=null","precio_tradeinn":0,"scrape_amazon":"https:\/\/www.amazon.es\/dp\/B0FX4M8T89","url_amazon":"https:\/\/www.amazon.es\/dp\/B0FX4M8T89?&tag=tennis-hack-21","precio_amazon":327.6,"scrape_decathlon":"","url_decathlon":"https:\/\/afiliacion.decathlon.es\/tracking\/clk?act=11229&gel=0&pub=31646&org=2615&url=null","precio_decathlon":0,"scrape_elcorteingles":"","url_elcorteingles":"https:\/\/www.awin1.com\/cread.php?awinmid=13075&awinaffid=1038971&ued=null","precio_elcorteingles":0,"scrape_tennispoint":"https:\/\/www.tennis-point.es\/products\/nox-genius-18k-alum-pala-de-padel-p0000001210401?_pos=1&_sid=7345c396d&_ss=r","url_tennispoint":"https:\/\/www.awin1.com\/cread.php?awinmid=13033&awinaffid=1038971&ued=https:\/\/www.tennis-point.es\/products\/nox-genius-18k-alum-pala-de-padel-p0000001210401?_pos=1&_sid=7345c396d&_ss=r","precio_tennispoint":390,"scrape_miravia":"","url_miravia":"https:\/\/www.awin1.com\/cread.php?awinmid=37168&awinaffid=1622959&ued=null","precio_miravia":0,"scrape_padelmarket":"https:\/\/padelmarket.com\/es-eu\/products\/nox-at10-genius-18k-alum-2026-by-agustin-tapia-pala","url_padelmarket":"https:\/\/www.awin1.com\/cread.php?awinmid=24562&awinaffid=1038971&ued=https:\/\/padelmarket.com\/es-eu\/products\/nox-at10-genius-18k-alum-2026-by-agustin-tapia-pala","precio_padelmarket":390,"scrape_padelproshop":"https:\/\/padelproshop.com\/products\/pala-nox-at10-genuis-18k-alum-by-agustin-tapia","url_padelproshop":"https:\/\/pin.padelproshop.com\/t\/t?a=1883995083&as=1904223805&t=2&tk=1&url=https:\/\/padelproshop.com\/products\/pala-nox-at10-genuis-18k-alum-by-agustin-tapia","precio_padelproshop":390,"scrape_padelnuestro":"","url_padelnuestro":"","precio_padelnuestro":0,"scrape_virtualpadel":"","url_virtualpadel":"","precio_virtualpadel":0,"scrape_todopadel":"","url_todopadel":"","precio_todopadel":0,"scrape_streetpadel":"","url_streetpadel":"","precio_streetpadel":0,"scrape_m1padel":"","url_m1padel":"","precio_m1padel":0,"scrape_padeliberico":"","url_padeliberico":"","precio_padeliberico":0,"scrape_padelreference":"","url_padelreference":"","precio_padelreference":0,"scrape_tennispro":"","url_tennispro":"","precio_tennispro":0,"scrape_forumsport":"","url_forumsport":"","precio_forumsport":0,"scrape_aliexpress":"","url_aliexpress":"","precio_aliexpress":0,"scrape_padelmania":"","url_padelmania":"","precio_padelmania":0,"scrape_worten":"","url_worten":"","precio_worten":0,"scrape_alvarez":"","url_alvarez":"","precio_alvarez":0,"scrape_tiendapadelpoint":"","url_tiendapadelpoint":"","precio_tiendapadelpoint":0,"scrape_padelstyle":"","url_padelstyle":"","precio_padelstyle":0,"scrape_atmosferasport":"","url_atmosferasport":"","precio_atmosferasport":0,"scrape_zonapadel":"","url_zonapadel":"","precio_zonapadel":0,"scrape_padeltienda":"","url_padeltienda":"","precio_padeltienda":0,"scrape_padelpoint":"","url_padelpoint":"","precio_padelpoint":0,"scrape_sprinter":"","url_sprinter":"","precio_sprinter":0,"scrape_carrefour":"","url_carrefour":"","precio_carrefour":0,"scrape_stockpadel":"","url_stockpadel":"","precio_stockpadel":0,"scrape_ofertasdepadel":"","url_ofertasdepadel":"","precio_ofertasdepadel":0,"scrape_padelspain":"","url_padelspain":"","precio_padelspain":0,"scrape_padel5":"","url_padel5":"","precio_padel5":0,"scrape_tenisworldpadel":"","url_tenisworldpadel":"","precio_tenisworldpadel":0,"scrape_megadeportes":"","url_megadeportes":"","precio_megadeportes":0,"scrape_paleteros":"","url_paleteros":"","precio_paleteros":0,"scrape_sportit":"","url_sportit":"","precio_sportit":0,"scrape_privatesportshop":"","url_privatesportshop":"","precio_privatesportshop":0,"scrape_jrpadel":"","url_jrpadel":"","precio_jrpadel":0,"scrape_padelever":"","url_padelever":"","precio_padelever":0,"scrape_topgame":"","url_topgame":"","precio_topgame":0,"scrape_coronado":"","url_coronado":"","precio_coronado":0,"scrape_adubasport":"https:\/\/adubasport.com\/pala-de-padel-nox-at10-genius-18k-alum-2026\/","url_adubasport":"https:\/\/adubasport.com\/pala-de-padel-nox-at10-genius-18k-alum-2026\/","precio_adubasport":390,"scrape_originalpadel":"","url_originalpadel":"","precio_originalpadel":0,"scrape_racketstore":"","url_racketstore":"","precio_racketstore":0,"scrape_matchballshop":"","url_matchballshop":"","precio_matchballshop":0,"scrape_wilson":"","url_wilson":"","precio_wilson":0,"scrape_pelotapadel":"","url_pelotapadel":"","precio_pelotapadel":0,"scrape_palapadelpro":"","url_palapadelpro":"","precio_palapadelpro":0,"scrape_viladomat":"","url_viladomat":"","precio_viladomat":0},"Campo_personalizado":null,"custom_uri":"raquettes-padel\/nox\/nox-at10-luxury-genius-18k-alum-agustin-tapia-2026","_links":{"self":[{"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/pala\/76669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/pala"}],"about":[{"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/types\/pala"}],"author":[{"embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/comments?post=76669"}],"version-history":[{"count":1,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/pala\/76669\/revisions"}],"predecessor-version":[{"id":90422,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/pala\/76669\/revisions\/90422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/media\/76727"}],"wp:attachment":[{"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/media?parent=76669"}],"wp:term":[{"taxonomy":"marca_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/marca_pala?post=76669"},{"taxonomy":"tipo_jugador","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/tipo_jugador?post=76669"},{"taxonomy":"forma_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/forma_pala?post=76669"},{"taxonomy":"nivel_jugador","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/nivel_jugador?post=76669"},{"taxonomy":"balance_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/balance_pala?post=76669"},{"taxonomy":"tacto_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/tacto_pala?post=76669"},{"taxonomy":"superficie_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/superficie_pala?post=76669"},{"taxonomy":"tipo_juego","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/tipo_juego?post=76669"},{"taxonomy":"pros_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/pros_pala?post=76669"},{"taxonomy":"contras_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/contras_pala?post=76669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}