{"id":48614,"date":"2025-01-17T20:46:23","date_gmt":"2025-01-17T20:46:23","guid":{"rendered":"https:\/\/pala-hack.com\/palas-padel\/adidas-metalbone-carbon-3-4-2025\/"},"modified":"2026-02-09T20:58:59","modified_gmt":"2026-02-09T20:58:59","slug":"adidas-metalbone-carbon-3-4-2025","status":"publish","type":"pala","link":"https:\/\/pala-hack.com\/fr\/raquettes-padel\/adidas\/adidas-metalbone-carbon-34-2025\/","title":{"rendered":"Adidas Metalbone Carbon 3.4 2025"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Pala<\/p>\n","protected":false},"author":1,"featured_media":48882,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"marca_pala":[505],"tipo_jugador":[684,665],"forma_pala":[690],"nivel_jugador":[719],"balance_pala":[738],"tacto_pala":[756],"superficie_pala":[789],"tipo_juego":[805],"pros_pala":[],"contras_pala":[],"class_list":["post-48614","pala","type-pala","status-publish","has-post-thumbnail","hentry","marca_pala-adidas","tipo_jugador-femme","tipo_jugador-homme","forma_pala-diamant","nivel_jugador-avance","balance_pala-eleve","tacto_pala-souple","superficie_pala-rugueuse","tipo_juego-puissance"],"acf":{"nucleo":"Eva Soft Performance","cara":"Carbon 6k","marco":"","acabado":"Relieve 3D","temporada":2025,"potencia":8.75,"punto_dulce":8.25,"salida_bola":9.75,"control":8.25,"manejabilidad":8,"puntuacion_total":8.6,"analisis":"","pvpr":260,"mejor_precio_url":"https:\/\/www.amazon.es\/adidas-AR1AA2U42-Adidas-padel\/dp\/B0DMCWSDW6?&tag=tennis-hack-21","mejor_precio":202.8,"disponibilidad":1,"porcentaje_descuento":22,"scrape_tradeinn":"https:\/\/www.tradeinn.com\/smashinn\/es\/adidas-pala-de-padel-metalbone-carbon-3.4-2025\/141477288\/p?queryID=46672562396ca4a878f6d66f329b32e4&buscador_search","url_tradeinn":"https:\/\/tnkdbf.tradeinn.com\/ts\/i5034676\/tsc?amc=con.blbn.503976.515016.14119793&rmd=3&trg=https:\/\/www.tradeinn.com\/smashinn\/es\/adidas-pala-de-padel-metalbone-carbon-3.4-2025\/141477288\/p?queryID=46672562396ca4a878f6d66f329b32e4&buscador_search","precio_tradeinn":260,"scrape_amazon":"https:\/\/www.amazon.es\/adidas-AR1AA2U42-Adidas-padel\/dp\/B0DMCWSDW6","url_amazon":"https:\/\/www.amazon.es\/adidas-AR1AA2U42-Adidas-padel\/dp\/B0DMCWSDW6?&tag=tennis-hack-21","precio_amazon":202.8,"scrape_decathlon":"0","url_decathlon":"https:\/\/afiliacion.decathlon.es\/tracking\/clk?act=11229&gel=0&pub=31646&org=2615&url=https:\/\/www.decathlon.es\/es\/p\/pala-de-padel-adulto-adidas-metalbone-carbon-3-3\/_\/R-p-355914?mc=8941409","precio_decathlon":0,"scrape_elcorteingles":"","url_elcorteingles":"https:\/\/www.awin1.com\/cread.php?awinmid=13075&awinaffid=1038971&ued=null","precio_elcorteingles":0,"scrape_tennispoint":"https:\/\/www.tennis-point.es\/adidas-metalbone-carbon-3.4-0050750021900000.html","url_tennispoint":"https:\/\/www.awin1.com\/cread.php?awinmid=13033&awinaffid=1038971&ued=https:\/\/www.tennis-point.es\/adidas-metalbone-carbon-3.4-0050750021900000.html","precio_tennispoint":260,"scrape_miravia":"https:\/\/www.miravia.es\/p\/i1367028272490822-s2084630605736262.html?siteRegion=es&sv_campaign_id=1608386&awc=37168_1742319324_1b8ad3a96ad9634386a11c60aa2b4c11&&publishertagid=967122&sitename=&affiliatedomain=&publishertagname1=ComparisonSiteGG&exlaz=d_a:mm_100000094_2000000080_3000000095:clkgg778s1iml563ictgf7::","url_miravia":"https:\/\/www.awin1.com\/cread.php?awinmid=37168&awinaffid=1622959&ued=https:\/\/www.miravia.es\/p\/i1367028272490822-s2084630605736262.html?siteRegion=es&sv_campaign_id=1608386&awc=37168_1742319324_1b8ad3a96ad9634386a11c60aa2b4c11&&publishertagid=967122&sitename=&affiliatedomain=&publishertagname1=ComparisonSiteGG&exlaz=d_a:mm_100000094_2000000080_3000000095:clkgg778s1iml563ictgf7::","precio_miravia":260,"scrape_padelmarket":"https:\/\/padelmarket.com\/en-eu\/products\/adidas-metalbone-3-3-2024-ale-galan-racket?_pos=2&_sid=39e45e211&_ss=r","url_padelmarket":"https:\/\/www.awin1.com\/cread.php?awinmid=24562&awinaffid=1038971&ued=https:\/\/padelmarket.com\/en-eu\/products\/adidas-metalbone-3-3-2024-ale-galan-racket?_pos=2&_sid=39e45e211&_ss=r","precio_padelmarket":260,"scrape_padelproshop":"https:\/\/padelproshop.com\/products\/pala-adidas-metalbone-carbon-3-4-2025","url_padelproshop":"https:\/\/pin.padelproshop.com\/t\/t?a=1883995083&as=1904223805&t=2&tk=1&url=https:\/\/padelproshop.com\/products\/pala-adidas-metalbone-carbon-3-4-2025","precio_padelproshop":260,"scrape_padelnuestro":"","url_padelnuestro":"","precio_padelnuestro":"","scrape_virtualpadel":"","url_virtualpadel":"","precio_virtualpadel":"","scrape_todopadel":"","url_todopadel":"","precio_todopadel":"","scrape_streetpadel":"","url_streetpadel":"","precio_streetpadel":"","scrape_m1padel":"","url_m1padel":"","precio_m1padel":"","scrape_padeliberico":"","url_padeliberico":"","precio_padeliberico":"","scrape_padelreference":"","url_padelreference":"","precio_padelreference":"","scrape_tennispro":"","url_tennispro":"","precio_tennispro":"","scrape_forumsport":"","url_forumsport":"","precio_forumsport":"","scrape_aliexpress":"","url_aliexpress":"","precio_aliexpress":"","scrape_padelmania":"","url_padelmania":"","precio_padelmania":"","scrape_worten":"","url_worten":"","precio_worten":"","scrape_alvarez":"","url_alvarez":"","precio_alvarez":"","scrape_tiendapadelpoint":"","url_tiendapadelpoint":"","precio_tiendapadelpoint":"","scrape_padelstyle":"","url_padelstyle":"","precio_padelstyle":"","scrape_atmosferasport":"","url_atmosferasport":"","precio_atmosferasport":"","scrape_zonapadel":"","url_zonapadel":"","precio_zonapadel":"","scrape_padeltienda":"","url_padeltienda":"","precio_padeltienda":"","scrape_padelpoint":"","url_padelpoint":"","precio_padelpoint":"","scrape_sprinter":"","url_sprinter":"","precio_sprinter":"","scrape_carrefour":"","url_carrefour":"","precio_carrefour":"","scrape_stockpadel":"","url_stockpadel":"","precio_stockpadel":"","scrape_ofertasdepadel":"","url_ofertasdepadel":"","precio_ofertasdepadel":"","scrape_padelspain":"","url_padelspain":"","precio_padelspain":"","scrape_padel5":"","url_padel5":"","precio_padel5":"","scrape_tenisworldpadel":"","url_tenisworldpadel":"","precio_tenisworldpadel":"","scrape_megadeportes":"","url_megadeportes":"","precio_megadeportes":"","scrape_paleteros":"","url_paleteros":"","precio_paleteros":"","scrape_sportit":"","url_sportit":"","precio_sportit":"","scrape_privatesportshop":"","url_privatesportshop":"","precio_privatesportshop":"","scrape_jrpadel":"","url_jrpadel":"","precio_jrpadel":"","scrape_padelever":"","url_padelever":"","precio_padelever":"","scrape_topgame":"","url_topgame":"","precio_topgame":"","scrape_coronado":"","url_coronado":"","precio_coronado":"","scrape_adubasport":"","url_adubasport":"","precio_adubasport":"","scrape_originalpadel":"","url_originalpadel":"","precio_originalpadel":"","scrape_racketstore":"","url_racketstore":"","precio_racketstore":"","scrape_matchballshop":"","url_matchballshop":"","precio_matchballshop":"","scrape_wilson":"","url_wilson":"","precio_wilson":"","scrape_pelotapadel":"","url_pelotapadel":"","precio_pelotapadel":"","scrape_palapadelpro":"","url_palapadelpro":"","precio_palapadelpro":"","scrape_viladomat":"","url_viladomat":"","precio_viladomat":""},"Campo_personalizado":null,"custom_uri":"raquettes-padel\/adidas\/adidas-metalbone-carbon-34-2025","_links":{"self":[{"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/pala\/48614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/pala"}],"about":[{"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/types\/pala"}],"author":[{"embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/comments?post=48614"}],"version-history":[{"count":1,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/pala\/48614\/revisions"}],"predecessor-version":[{"id":50022,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/pala\/48614\/revisions\/50022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/media\/48882"}],"wp:attachment":[{"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/media?parent=48614"}],"wp:term":[{"taxonomy":"marca_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/marca_pala?post=48614"},{"taxonomy":"tipo_jugador","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/tipo_jugador?post=48614"},{"taxonomy":"forma_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/forma_pala?post=48614"},{"taxonomy":"nivel_jugador","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/nivel_jugador?post=48614"},{"taxonomy":"balance_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/balance_pala?post=48614"},{"taxonomy":"tacto_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/tacto_pala?post=48614"},{"taxonomy":"superficie_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/superficie_pala?post=48614"},{"taxonomy":"tipo_juego","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/tipo_juego?post=48614"},{"taxonomy":"pros_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/pros_pala?post=48614"},{"taxonomy":"contras_pala","embeddable":true,"href":"https:\/\/pala-hack.com\/fr\/wp-json\/wp\/v2\/contras_pala?post=48614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}